{"id":122,"count":30,"description":"","link":"https:\/\/sigvape.com\/sk\/product-category\/30000-puffs-disposable-vape\/","name":"30000 potiahnut\u00ed jednorazov\u00e1 vape","slug":"30000-puffs-disposable-vape","taxonomy":"product_cat","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>30000 Puffs Disposable Vape Archives - sigvape.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sigvape.com\/sk\/product-category\/30000-puffs-disposable-vape\/\" \/>\n<meta property=\"og:locale\" content=\"sk_SK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"30000 Puffs Disposable Vape Archives - sigvape.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sigvape.com\/sk\/product-category\/30000-puffs-disposable-vape\/\" \/>\n<meta property=\"og:site_name\" content=\"sigvape.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/sigvape.com\/product-category\/30000-puffs-disposable-vape\/\",\"url\":\"https:\/\/sigvape.com\/product-category\/30000-puffs-disposable-vape\/\",\"name\":\"30000 Puffs Disposable Vape Archives - sigvape.com\",\"isPartOf\":{\"@id\":\"https:\/\/sigvape.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/sigvape.com\/product-category\/30000-puffs-disposable-vape\/#breadcrumb\"},\"inLanguage\":\"sk-SK\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sigvape.com\/product-category\/30000-puffs-disposable-vape\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/sigvape.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"30000 Puffs Disposable Vape\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sigvape.com\/#website\",\"url\":\"https:\/\/sigvape.com\/\",\"name\":\"sigvape.com\",\"description\":\"vape wholesale bulk price\",\"publisher\":{\"@id\":\"https:\/\/sigvape.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sigvape.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"sk-SK\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sigvape.com\/#organization\",\"name\":\"sigvape.com\",\"url\":\"https:\/\/sigvape.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sk-SK\",\"@id\":\"https:\/\/sigvape.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sigvape.com\/wp-content\/uploads\/2023\/08\/cropped-cropped-cropped-cropped-sigvape-retail-price-1.png\",\"contentUrl\":\"https:\/\/sigvape.com\/wp-content\/uploads\/2023\/08\/cropped-cropped-cropped-cropped-sigvape-retail-price-1.png\",\"width\":336,\"height\":316,\"caption\":\"sigvape.com\"},\"image\":{\"@id\":\"https:\/\/sigvape.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"30000 Puffs Disposable Vape Archives - sigvape.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sigvape.com\/sk\/product-category\/30000-puffs-disposable-vape\/","og_locale":"sk_SK","og_type":"article","og_title":"30000 Puffs Disposable Vape Archives - sigvape.com","og_url":"https:\/\/sigvape.com\/sk\/product-category\/30000-puffs-disposable-vape\/","og_site_name":"sigvape.com","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/sigvape.com\/product-category\/30000-puffs-disposable-vape\/","url":"https:\/\/sigvape.com\/product-category\/30000-puffs-disposable-vape\/","name":"30000 Puffs Disposable Vape Archives - sigvape.com","isPartOf":{"@id":"https:\/\/sigvape.com\/#website"},"breadcrumb":{"@id":"https:\/\/sigvape.com\/product-category\/30000-puffs-disposable-vape\/#breadcrumb"},"inLanguage":"sk-SK"},{"@type":"BreadcrumbList","@id":"https:\/\/sigvape.com\/product-category\/30000-puffs-disposable-vape\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sigvape.com\/"},{"@type":"ListItem","position":2,"name":"30000 Puffs Disposable Vape"}]},{"@type":"WebSite","@id":"https:\/\/sigvape.com\/#website","url":"https:\/\/sigvape.com\/","name":"sigvape.com","description":"vape wholesale bulk price","publisher":{"@id":"https:\/\/sigvape.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sigvape.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"sk-SK"},{"@type":"Organization","@id":"https:\/\/sigvape.com\/#organization","name":"sigvape.com","url":"https:\/\/sigvape.com\/","logo":{"@type":"ImageObject","inLanguage":"sk-SK","@id":"https:\/\/sigvape.com\/#\/schema\/logo\/image\/","url":"https:\/\/sigvape.com\/wp-content\/uploads\/2023\/08\/cropped-cropped-cropped-cropped-sigvape-retail-price-1.png","contentUrl":"https:\/\/sigvape.com\/wp-content\/uploads\/2023\/08\/cropped-cropped-cropped-cropped-sigvape-retail-price-1.png","width":336,"height":316,"caption":"sigvape.com"},"image":{"@id":"https:\/\/sigvape.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sigvape.com\/sk\/wp-json\/wp\/v2\/product_cat\/122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sigvape.com\/sk\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/sigvape.com\/sk\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/sigvape.com\/sk\/wp-json\/wp\/v2\/product?product_cat=122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}