{"id":1832,"date":"2024-09-12T10:23:53","date_gmt":"2024-09-12T08:23:53","guid":{"rendered":"https:\/\/sigvape.com\/?post_type=product&#038;p=1832"},"modified":"2024-10-22T11:52:16","modified_gmt":"2024-10-22T09:52:16","slug":"waspe-vapes-25000-puffs-aiviou-bulk-price-cheap-smart-vapes-blueteeth-screen","status":"publish","type":"product","link":"https:\/\/sigvape.com\/fr\/product\/waspe-vapes-25000-puffs-aiviou-bulk-price-cheap-smart-vapes-blueteeth-screen\/","title":{"rendered":"Waspe Vapes 25000 Puffs AIviou Prix de gros bon march\u00e9 Vapes intelligentes \u00c9cran Blueteeth"},"content":{"rendered":"<h1>Waspe Vapes 25000 Puffs AIviou Prix de gros bon march\u00e9 Vapes intelligentes \u00c9cran Blueteeth<\/h1>\n<p>Le Waspe 25k est con\u00e7u pour les vapoteurs s\u00e9rieux qui appr\u00e9cient les appareils durables et performants. Avec <strong>25000 bouff\u00e9es<\/strong>, ce vape jetable vous assure une utilisation prolong\u00e9e avant d'avoir besoin d'un remplacement. Son design \u00e9pur\u00e9 et moderne int\u00e8gre un <strong>\u00e9cran LCD intelligent<\/strong>, vous donnant des informations claires et en temps r\u00e9el sur l'\u00e9tat de la batterie et le nombre de bouff\u00e9es, vous assurant d'avoir toujours le contr\u00f4le de votre exp\u00e9rience de vapotage.<\/p>\n<p>La cl\u00e9 de sa performance fluide et constante est la <strong>technologie de double bobine en maille<\/strong>, qui d\u00e9livre une production de vapeur am\u00e9lior\u00e9e et une saveur riche \u00e0 chaque inhalation. La <strong>batterie rechargeable int\u00e9gr\u00e9e de 650 mAh<\/strong> offre une puissance fiable, tandis que le <strong>port de charge Type-C<\/strong> assure des recharges rapides et efficaces, pour que vous puissiez reprendre le vapotage plus rapidement.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-1828\" src=\"http:\/\/sigvape.com\/wp-content\/uploads\/2024\/09\/FIHP-WASPE-25000-puffs-vape-Wholesale-Price-300x175.jpg\" alt=\"FIHP WASPE 25000 puffs vape Prix de gros\" width=\"300\" height=\"175\" srcset=\"https:\/\/sigvape.com\/wp-content\/uploads\/2024\/09\/FIHP-WASPE-25000-puffs-vape-Wholesale-Price-300x175.jpg 300w, https:\/\/sigvape.com\/wp-content\/uploads\/2024\/09\/FIHP-WASPE-25000-puffs-vape-Wholesale-Price-768x448.jpg 768w, https:\/\/sigvape.com\/wp-content\/uploads\/2024\/09\/FIHP-WASPE-25000-puffs-vape-Wholesale-Price-600x350.jpg 600w, https:\/\/sigvape.com\/wp-content\/uploads\/2024\/09\/FIHP-WASPE-25000-puffs-vape-Wholesale-Price.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h1>Format des vapes Waspe 25000 bouff\u00e9es :<\/h1>\n<p><span style=\"font-family: var(--global-body-font-family);\">&#8211;<\/span><span style=\"color: #ff0000;\">2%\/5% Nicotine<\/span><span style=\"font-family: var(--global-body-font-family);\">:<\/span><em style=\"font-family: var(--global-body-font-family);\">Le taux de nicotine de 2% est relativement faible<\/em><\/p>\n<p>&#8211;<span style=\"color: #ff0000;\">25 ML de E-liquide<span style=\"color: #000000;\">:<em>La quantit\u00e9 d'e-liquide est suffisante pour satisfaire l'utilisateur<\/em><\/span><\/span><\/p>\n<p>&#8211;<span style=\"color: #ff0000;\">25000 bouff\u00e9es<span style=\"color: #000000;\">:<em>le nombre de bouff\u00e9es d\u00e9pend du choix de l'utilisateur<\/em><\/span><\/span><\/p>\n<p>&#8211;<span style=\"color: #ff0000;\">Batterie rechargeable (Type-C)<span style=\"color: #000000;\">:<em>charge pratique<\/em><\/span><\/span><\/p>\n<p>&#8211;<span style=\"color: #ff0000;\">Batterie de 650mAh<span style=\"color: #000000;\">:<em>r\u00e9duit les temps de charge<\/em><\/span><\/span><\/p>\n<p>&#8211;<span style=\"color: #ff0000;\">10 Saveurs<span style=\"color: #000000;\">Vari\u00e9t\u00e9 de saveurs<\/span><\/span><\/p>\n<h1>Liste des saveurs des vapes Waspe 25k bouff\u00e9es :<\/h1>\n<p>1.Fraise Kiwi<\/p>\n<p>2.Baies m\u00e9lang\u00e9es<\/p>\n<p>3.Myrtille sur glace<\/p>\n<p>4.Raisin glac\u00e9<\/p>\n<p>5.Cerise glac\u00e9e<\/p>\n<p>6.Limonade Myrtille Framboise<\/p>\n<p>7.P\u00eache Glace<\/p>\n<p>8.Fraise Past\u00e8que<\/p>\n<p>9.P\u00eache Mangue Past\u00e8que<\/p>\n<p>10.Past\u00e8que glac\u00e9e<\/p>\n<h1>Questions que vous pourriez vouloir poser sur le Waspe 25k bouff\u00e9es :<\/h1>\n<p><strong>1. Combien de temps dure le Waspe 25000 bouff\u00e9es ?<\/strong><br \/>\nLe Waspe 25k offre 25000 bouff\u00e9es, ce qui peut durer plusieurs semaines, selon vos habitudes de vapotage. Il est con\u00e7u pour une utilisation prolong\u00e9e avant de devoir \u00eatre remplac\u00e9.<\/p>\n<p><strong>2. Le Waspe Vape 25000 bouff\u00e9es peut-il \u00eatre recharg\u00e9 ?<\/strong><br \/>\nOui, le Waspe 25k est \u00e9quip\u00e9 d'un <strong>La batterie rechargeable de 650 mAh<\/strong> et d'un <strong>port de charge Type-C<\/strong> pour une recharge rapide. Vous pouvez continuer \u00e0 utiliser l'appareil jusqu'\u00e0 ce que l'e-liquide soit \u00e9puis\u00e9.<\/p>\n<p><strong>3. Quelle est la capacit\u00e9 en e-liquide du Waspe 25k Vape ?<\/strong><br \/>\nLe Waspe 25k est livr\u00e9 avec une capacit\u00e9 de <strong>25 ml<\/strong> d'e-liquide, offrant une quantit\u00e9 substantielle de liquide de vapotage pour supporter ses 25000 bouff\u00e9es.<\/p>\n<p><strong>4. Y a-t-il diff\u00e9rents niveaux de nicotine disponibles pour le Waspe 25k Vape?<\/strong><br \/>\nOui, le Waspe 25k offre une flexibilit\u00e9 avec les niveaux de nicotine, disponibles en <strong>0%, 2% ou 5% de nicotine<\/strong> pour convenir \u00e0 vos pr\u00e9f\u00e9rences personnelles.<\/p>\n<p><strong>5. Quels ar\u00f4mes sont disponibles pour le Vape Waspe 25000 Puffs?<\/strong><br \/>\nLe Waspe 25k est disponible en 10 ar\u00f4mes passionnants, notamment Fraise Kiwi, Baies m\u00e9lang\u00e9es, Raisin Glac\u00e9, Myrtille Framboise Limonade, et plus encore.<\/p>\n<p><strong>6. Combien d'appareils Waspe 25000 Puffs sont livr\u00e9s dans un paquet de gros?<\/strong><br \/>\nChaque carton contient <strong>200 unit\u00e9s<\/strong>, ce qui le rend id\u00e9al pour les achats en gros. Mais l'achat chez Sigvape ne n\u00e9cessite que 50 pi\u00e8ces pour d\u00e9marrer votre entreprise.<\/p>\n<p><strong>7. Quel type de bobine le Waspe 25k utilise-t-il?<\/strong><br \/>\nL'appareil est \u00e9quip\u00e9 de <strong>bobines \u00e0 double maille<\/strong>, qui fournissent une vapeur plus douce et une meilleure saveur \u00e0 chaque bouff\u00e9e.<\/p>\n<p>Trouvez d'autres produits que vous pourriez aimer :<em><a href=\"https:\/\/wa.me\/8617840853976\">acheter maintenant<\/a><\/em><\/p>\n<p>autres bouff\u00e9es que vous pourriez aimer :<strong><a href=\"https:\/\/sigvape.com\/fr\/product\/popular-vape-bang-20000puffs-hot-sale-vape\/\">Bang 20k bouff\u00e9es<\/a><\/strong>\/<strong><a href=\"https:\/\/sigvape.com\/fr\/product\/waspe-15000-puffs-tornado-bulk-price-15k-vape\/\">Vapes Waspe 15000<\/a>\/<a href=\"https:\/\/sigvape.com\/fr\/product\/wholesale-authentic-price-bang-box-12000-puffs-tornado-12k-price\/\">Bang tornade 12k<\/a>\/<a href=\"https:\/\/sigvape.com\/fr\/product\/all-flavors-vapme-crystal-7000-puffs-wholesale-price\/\">Vape Cristal<\/a><\/strong><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-836\" src=\"http:\/\/sigvape.com\/wp-content\/uploads\/2023\/08\/whatsapp-169x300.jpg\" alt=\"whatsapp+(86)15705601249\" width=\"169\" height=\"300\" srcset=\"https:\/\/sigvape.com\/wp-content\/uploads\/2023\/08\/whatsapp-169x300.jpg 169w, https:\/\/sigvape.com\/wp-content\/uploads\/2023\/08\/whatsapp.jpg 540w\" sizes=\"(max-width: 169px) 100vw, 169px\" \/><\/p>\n<h6><strong>Scannez pour obtenir plus de r\u00e9ductions<\/strong><\/h6>\n<h3>Pourquoi acheter en gros le WASPE 25000 Puffs chez <a href=\"https:\/\/sigvape.com\/fr\/shop\/\">Sigvape.com<\/a><\/h3>\n<p>Chez Sigvape, nous veillons \u00e0 ce que tous nos appareils Waspe 25000 Puffs soient de la plus haute qualit\u00e9, avec des processus de contr\u00f4le qualit\u00e9 stricts en place. Lors d'un achat en gros chez nous, vous b\u00e9n\u00e9ficiez de :<\/p>\n<ul>\n<li><strong>Prix comp\u00e9titifs :<\/strong> Profitez d'\u00e9conomies de co\u00fbts importantes lors de l'achat en vrac.<\/li>\n<li><strong>Large s\u00e9lection d'ar\u00f4mes :<\/strong> Un large \u00e9ventail d'options de saveurs vous permet de r\u00e9pondre \u00e0 diff\u00e9rentes pr\u00e9f\u00e9rences des clients.<\/li>\n<li><strong>Livraison rapide :<\/strong> Nous offrons une exp\u00e9dition rapide et fiable pour assurer une livraison dans les d\u00e9lais.<\/li>\n<li><strong>Service client :<\/strong> Notre \u00e9quipe d\u00e9di\u00e9e est disponible pour vous aider avec les commandes, les questions sur les produits et le service apr\u00e8s-vente.<\/li>\n<li><strong>Fournisseur de confiance :<\/strong> Sigvape jouit d'une solide r\u00e9putation dans l'industrie de la vape pour ne fournir que les meilleurs produits, vous donnant la tranquillit\u00e9 d'esprit lors de l'achat.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<h3>Achat en gros WASPE 25000 Puffs<\/h3>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-836\" src=\"http:\/\/sigvape.com\/wp-content\/uploads\/2023\/08\/whatsapp-169x300.jpg\" alt=\"whatsapp+(86)15705601249\" width=\"169\" height=\"300\" srcset=\"https:\/\/sigvape.com\/wp-content\/uploads\/2023\/08\/whatsapp-169x300.jpg 169w, https:\/\/sigvape.com\/wp-content\/uploads\/2023\/08\/whatsapp.jpg 540w\" sizes=\"(max-width: 169px) 100vw, 169px\" \/><\/p>\n<p>Ajouter Whatsapp pour une offre sp\u00e9ciale<span style=\"color: #ff0000;\">:<em><strong><a style=\"color: #ff0000;\" href=\"https:\/\/wa.me\/8615705601249\">+86 1<\/a>5705601249<\/strong><\/em><\/span><\/p>","protected":false},"featured_media":1830,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_lmt_disableupdate":"no","_lmt_disable":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"default","_kad_post_title":"","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_joinchat":[]},"product_cat":[35,69,79,72,36,25,93],"product_tag":[59,90,48,89,70,47],"class_list":["post-1832","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-france-vape-hot-sale","product_cat-german-vape-hot-sale","product_cat-jnr-shisha-15k-puffs","product_cat-moq-50pcs","product_cat-netherlands-vape-hot-sale","product_cat-vape-hot-sale-this-week","product_cat-waspe-vape","product_tag-bulk-price","product_tag-discount-price","product_tag-good-review","product_tag-moq-50pcs","product_tag-vape-wholesale","product_tag-wholesale-price","entry","content-bg","loop-entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Waspe Vapes 25000 Puffs AIviou Bulk Price Cheap Smart Vapes Blueteeth Screen - sigvape.com<\/title>\n<meta name=\"description\" content=\"Buy Waspe Vapes 25000 Puffs at Sigvape,Get Discount Price of 25000 puffs vape OnlyToday!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sigvape.com\/fr\/product\/waspe-vapes-25000-puffs-aiviou-bulk-price-cheap-smart-vapes-blueteeth-screen\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Waspe Vapes 25000 Puffs AIviou Bulk Price Cheap Smart Vapes Blueteeth Screen - sigvape.com\" \/>\n<meta property=\"og:description\" content=\"Buy Waspe Vapes 25000 Puffs at Sigvape,Get Discount Price of 25000 puffs vape OnlyToday!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sigvape.com\/fr\/product\/waspe-vapes-25000-puffs-aiviou-bulk-price-cheap-smart-vapes-blueteeth-screen\/\" \/>\n<meta property=\"og:site_name\" content=\"sigvape.com\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-22T09:52:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sigvape.com\/wp-content\/uploads\/2024\/09\/WASPE-FIHP-25000-puffs-vape-Supplier-Price.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sigvape.com\/sv\/product\/waspe-vapes-25000-puffs-aiviou-bulk-price-cheap-smart-vapes-blueteeth-screen\/\",\"url\":\"https:\/\/sigvape.com\/sv\/product\/waspe-vapes-25000-puffs-aiviou-bulk-price-cheap-smart-vapes-blueteeth-screen\/\",\"name\":\"Waspe Vapes 25000 Puffs AIviou Bulk Price Cheap Smart Vapes Blueteeth Screen - sigvape.com\",\"isPartOf\":{\"@id\":\"https:\/\/sigvape.com\/#website\"},\"datePublished\":\"2024-09-12T08:23:53+00:00\",\"dateModified\":\"2024-10-22T09:52:16+00:00\",\"description\":\"Buy Waspe Vapes 25000 Puffs at Sigvape,Get Discount Price of 25000 puffs vape OnlyToday!\",\"breadcrumb\":{\"@id\":\"https:\/\/sigvape.com\/sv\/product\/waspe-vapes-25000-puffs-aiviou-bulk-price-cheap-smart-vapes-blueteeth-screen\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sigvape.com\/sv\/product\/waspe-vapes-25000-puffs-aiviou-bulk-price-cheap-smart-vapes-blueteeth-screen\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sigvape.com\/sv\/product\/waspe-vapes-25000-puffs-aiviou-bulk-price-cheap-smart-vapes-blueteeth-screen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/sigvape.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/sigvape.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Waspe Vapes 25000 Puffs AIviou Bulk Price Cheap Smart Vapes Blueteeth Screen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sigvape.com\/#website\",\"url\":\"https:\/\/sigvape.com\/\",\"name\":\"sigvape.com\",\"description\":\"vape wholesale bulk price\",\"publisher\":{\"@id\":\"https:\/\/sigvape.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sigvape.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sigvape.com\/#organization\",\"name\":\"sigvape.com\",\"url\":\"https:\/\/sigvape.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/sigvape.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sigvape.com\/wp-content\/uploads\/2023\/08\/cropped-cropped-cropped-cropped-sigvape-retail-price-1.png\",\"contentUrl\":\"https:\/\/sigvape.com\/wp-content\/uploads\/2023\/08\/cropped-cropped-cropped-cropped-sigvape-retail-price-1.png\",\"width\":336,\"height\":316,\"caption\":\"sigvape.com\"},\"image\":{\"@id\":\"https:\/\/sigvape.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Waspe Vapes 25000 Puffs AIviou Bulk Price Cheap Smart Vapes Blueteeth Screen - sigvape.com","description":"Buy Waspe Vapes 25000 Puffs at Sigvape,Get Discount Price of 25000 puffs vape OnlyToday!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sigvape.com\/fr\/product\/waspe-vapes-25000-puffs-aiviou-bulk-price-cheap-smart-vapes-blueteeth-screen\/","og_locale":"fr_FR","og_type":"article","og_title":"Waspe Vapes 25000 Puffs AIviou Bulk Price Cheap Smart Vapes Blueteeth Screen - sigvape.com","og_description":"Buy Waspe Vapes 25000 Puffs at Sigvape,Get Discount Price of 25000 puffs vape OnlyToday!","og_url":"https:\/\/sigvape.com\/fr\/product\/waspe-vapes-25000-puffs-aiviou-bulk-price-cheap-smart-vapes-blueteeth-screen\/","og_site_name":"sigvape.com","article_modified_time":"2024-10-22T09:52:16+00:00","og_image":[{"width":600,"height":800,"url":"https:\/\/sigvape.com\/wp-content\/uploads\/2024\/09\/WASPE-FIHP-25000-puffs-vape-Supplier-Price.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sigvape.com\/sv\/product\/waspe-vapes-25000-puffs-aiviou-bulk-price-cheap-smart-vapes-blueteeth-screen\/","url":"https:\/\/sigvape.com\/sv\/product\/waspe-vapes-25000-puffs-aiviou-bulk-price-cheap-smart-vapes-blueteeth-screen\/","name":"Waspe Vapes 25000 Puffs AIviou Bulk Price Cheap Smart Vapes Blueteeth Screen - sigvape.com","isPartOf":{"@id":"https:\/\/sigvape.com\/#website"},"datePublished":"2024-09-12T08:23:53+00:00","dateModified":"2024-10-22T09:52:16+00:00","description":"Buy Waspe Vapes 25000 Puffs at Sigvape,Get Discount Price of 25000 puffs vape OnlyToday!","breadcrumb":{"@id":"https:\/\/sigvape.com\/sv\/product\/waspe-vapes-25000-puffs-aiviou-bulk-price-cheap-smart-vapes-blueteeth-screen\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sigvape.com\/sv\/product\/waspe-vapes-25000-puffs-aiviou-bulk-price-cheap-smart-vapes-blueteeth-screen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sigvape.com\/sv\/product\/waspe-vapes-25000-puffs-aiviou-bulk-price-cheap-smart-vapes-blueteeth-screen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sigvape.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/sigvape.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Waspe Vapes 25000 Puffs AIviou Bulk Price Cheap Smart Vapes Blueteeth Screen"}]},{"@type":"WebSite","@id":"https:\/\/sigvape.com\/#website","url":"https:\/\/sigvape.com\/","name":"sigvape.com","description":"vape wholesale bulk price","publisher":{"@id":"https:\/\/sigvape.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sigvape.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/sigvape.com\/#organization","name":"sigvape.com","url":"https:\/\/sigvape.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sigvape.com\/#\/schema\/logo\/image\/","url":"https:\/\/sigvape.com\/wp-content\/uploads\/2023\/08\/cropped-cropped-cropped-cropped-sigvape-retail-price-1.png","contentUrl":"https:\/\/sigvape.com\/wp-content\/uploads\/2023\/08\/cropped-cropped-cropped-cropped-sigvape-retail-price-1.png","width":336,"height":316,"caption":"sigvape.com"},"image":{"@id":"https:\/\/sigvape.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sigvape.com\/fr\/wp-json\/wp\/v2\/product\/1832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sigvape.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sigvape.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/sigvape.com\/fr\/wp-json\/wp\/v2\/comments?post=1832"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sigvape.com\/fr\/wp-json\/wp\/v2\/media\/1830"}],"wp:attachment":[{"href":"https:\/\/sigvape.com\/fr\/wp-json\/wp\/v2\/media?parent=1832"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sigvape.com\/fr\/wp-json\/wp\/v2\/product_cat?post=1832"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sigvape.com\/fr\/wp-json\/wp\/v2\/product_tag?post=1832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}